{"id":2045,"date":"2021-05-19T05:25:35","date_gmt":"2021-05-19T05:25:35","guid":{"rendered":"https:\/\/saq0hpur0o.wpdns.site\/?p=2045"},"modified":"2021-07-15T04:00:49","modified_gmt":"2021-07-15T04:00:49","slug":"all-you-need-to-know-about-sheet-metal-flame-correction","status":"publish","type":"post","link":"https:\/\/hecter.cn\/de\/all-you-need-to-know-about-sheet-metal-flame-correction\/","title":{"rendered":"Alles, was Sie \u00fcber die Flammenkorrektur bei Blechen wissen m\u00fcssen"},"content":{"rendered":"<p class=\"yoast-reading-time__wrapper\"><span class=\"yoast-reading-time__icon\"><\/span><span class=\"yoast-reading-time__descriptive-text\">Gesch\u00e4tzte Lesezeit:  <\/span><span class=\"yoast-reading-time__reading-time\">12<\/span><span class=\"yoast-reading-time__time-unit\"> Protokoll<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der thermischen Korrektur von <a href=\"https:\/\/www.hjsd-steelstructure.com\/news\/flame-correction-method-for-welding-deformation-of-steel-structure\" target=\"_blank\" rel=\"noopener\">Blech<\/a>, die am weitesten verbreitete ist die Acetylen-Sauerstoff-Flammenkorrektur. Die Flammenkorrektur wird nicht nur bei der Materialvorbereitung verwendet, sondern kann auch verwendet werden, um die Verformung der Struktur im Herstellungsprozess zu korrigieren. Da die Flammenkorrektur bequem und flexibel ist, sind die Kosten gering, so dass sie weit verbreitet ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Physikalische Eigenschaften von Blechmaterialien haben W\u00e4rmebilgen kaltschrumpfen, wenn lokales Erhitzen erhitztes Material erhitzt und aufgeblasen wird, aber aufgrund der niedrigen Temperatur der umgebenden Materialien wird daher die Erw\u00e4rmung des Metalls durch die Druckspannung behindert, wenn die Erw\u00e4rmungstemperatur 600 \u00b0 C betr\u00e4gt \u2013 700 \u2103, die Druckspannung \u00fcberschreitet die Streckgrenze des Materials bei der Temperatur, Druckverformung erzeugen. Wenn die Erw\u00e4rmung beendet wird, k\u00fchlt das Metall ab und verk\u00fcrzt sich. Dadurch sind die Metallfasern an der Erw\u00e4rmungsstelle k\u00fcrzer als die urspr\u00fcnglichen, wodurch eine neue Verformung entsteht. Die Flammenkorrektur dient dazu, die urspr\u00fcngliche Verformung zu korrigieren, indem die neue Verformung verwendet wird, die durch die lokale Erw\u00e4rmung des Metalls verursacht wird. Daher ist es der Schl\u00fcssel zur Beherrschung der Flammenkorrektur, um das Deformationsgesetz zu verstehen, das durch die lokale Erw\u00e4rmung der Flamme verursacht wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das folgende Bild zeigt die Verformung von Stahlblech, Winkelstahl und T-Stahl w\u00e4hrend und nach dem Erhitzen. Da die Metallfaser im Heizbereich nach dem Abk\u00fchlen gek\u00fcrzt werden soll, wird der Profilstahl zur Heizseite hin gebogen und verformt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Flammenkorrektur muss die durch Erw\u00e4rmung verursachte Verformung der urspr\u00fcnglichen Verformung entgegengesetzt sein, um die urspr\u00fcngliche Verformung auszugleichen und zu korrigieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die W\u00e4rmequelle der Flammenkorrekturheizung ist normalerweise eine Sauerstoff-Acetylen-Flamme, da die Temperatur der Sauerstoff-B-Schnellflamme hoch und die Heizgeschwindigkeit hoch ist.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/1-1.jpg\" alt=\"Verformung beim Erhitzen von Profilstahl\" class=\"wd-lazy-fade wp-image-2047\" width=\"469\" height=\"297\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/1-1.jpg 937w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/1-1-150x95.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/1-1-300x190.jpg 300w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/1-1-768x486.jpg 768w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/1-1-600x380.jpg 600w\" sizes=\"(max-width: 469px) 100vw, 469px\" \/><figcaption>Verformung beim Erhitzen von Profilstahl<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-operation-method-of-flame-correction\"><strong><a href=\"https:\/\/hecter.cn\/de\/what-is-the-sheet-metal-mechanical-correction\/\">Betriebsmethode der Flammenkorrektur<\/a><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Flammenkorrektur ist ein manueller Vorgang, der auf der Verformung des Werkst\u00fccks basieren muss, die Flammenheizposition, -zeit, -temperatur und andere Aspekte steuern muss, um einen besseren Korrektureffekt zu erzielen. Unterschiedliche Heizpositionen k\u00f6nnen die Verformung in verschiedene Richtungen korrigieren, und die Heizposition sollte im l\u00e4ngeren Teil der Metallfaser, dh au\u00dferhalb der Biegeverformung des Materials, gew\u00e4hlt werden. Dar\u00fcber hinaus hat die Form der Erw\u00e4rmungsfl\u00e4che am erw\u00e4rmten Werkst\u00fcck einen gro\u00dfen Einfluss auf Richtung und Ausma\u00df der Verformung des korrigierten Werkst\u00fccks und die Richtung der gr\u00f6\u00dften Faserl\u00e4ngendifferenz durch die Erw\u00e4rmungsfl\u00e4che am korrigierten Werkst\u00fcck in Richtung die gr\u00f6\u00dfte Biegeverformung des Werkst\u00fccks.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ausma\u00df der Verformung ist proportional zum L\u00e4ngenunterschied \u00fcber die Heizzone. Mit unterschiedlicher Flammenw\u00e4rme k\u00f6nnen Sie unterschiedliche F\u00e4higkeiten zur Korrektur der Verformung erhalten. Wenn die Hitze der Flamme nicht ausreicht, wird die Aufheizzeit verl\u00e4ngert, der Aufheizbereich wird erweitert und der Verformungsunterschied zwischen parallelen Fasern wird verringert, so dass es nicht einfach ist, sich zu begradigen konzentrierter die W\u00e4rme, desto st\u00e4rker die Korrekturf\u00e4higkeit und desto gr\u00f6\u00dfer die Korrekturdeformation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei kohlenstoffarmem Stahl und gew\u00f6hnlichem niedriglegiertem Stahl wird h\u00e4ufig eine Heiztemperatur von 600-80 \u00b0 C verwendet. Die allgemeine Heiztemperatur sollte 850 \u00b0 C nicht \u00fcberschreiten, um das Metall beim Heizen nicht zu \u00fcberhitzen, aber die Heiztemperatur darf nicht zu niedrig sein, da die Korrektureffizienz nicht hoch ist, wenn die Temperatur zu niedrig ist. Die Erw\u00e4rmungstemperatur kann grob anhand der Farbe der erw\u00e4rmten Stahloberfl\u00e4che in der Produktion beurteilt werden und ist erfahrungsgem\u00e4\u00df genau, wie in der Tabelle gezeigt.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Farbe<\/td><td class=\"has-text-align-center\" data-align=\"center\">Temperatur \/\u2103<\/td><td class=\"has-text-align-center\" data-align=\"center\">Farbe<\/td><td class=\"has-text-align-center\" data-align=\"center\">Temperatur \/\u2103<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Dunkelkastanienbraun<\/td><td class=\"has-text-align-center\" data-align=\"center\">550-580<\/td><td class=\"has-text-align-center\" data-align=\"center\">Helles Fuchsia<\/td><td class=\"has-text-align-center\" data-align=\"center\">830-900<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Kastanienbraun<\/td><td class=\"has-text-align-center\" data-align=\"center\">580-650<\/td><td class=\"has-text-align-center\" data-align=\"center\">Orange<\/td><td class=\"has-text-align-center\" data-align=\"center\">900-1050<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Dunkelfuchsia<\/td><td class=\"has-text-align-center\" data-align=\"center\">650-730<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dunkelgelb<\/td><td class=\"has-text-align-center\" data-align=\"center\">1050-1150<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Tiefes Fuchsia<\/td><td class=\"has-text-align-center\" data-align=\"center\">730-770<\/td><td class=\"has-text-align-center\" data-align=\"center\">Helles Gelb<\/td><td class=\"has-text-align-center\" data-align=\"center\">1150-1250<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Fuchsie<\/td><td class=\"has-text-align-center\" data-align=\"center\">770-800<\/td><td class=\"has-text-align-center\" data-align=\"center\">Wei\u00df Gelb<\/td><td class=\"has-text-align-center\" data-align=\"center\">1250-1300<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Hellfuchsia<\/td><td class=\"has-text-align-center\" data-align=\"center\">800-830<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><\/tbody><\/table><figcaption>Stahloberfl\u00e4chenfarbe und Schattentemperatur (geheim beobachtet)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Erw\u00e4rmungsmethoden an der Oberfl\u00e4che des verformten Werkst\u00fccks sind Punkterw\u00e4rmung, lineare Erw\u00e4rmung und Dreieckserw\u00e4rmung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Punktheizung bezieht sich auf den Punkt, an dem die Heizfl\u00e4che eine kreisf\u00f6rmige Fl\u00e4che mit einem bestimmten Durchmesser ist. Nach der Verformung von Stahl bestimmen Sie die Verteilung der Hot-Spots und der Hot-Spot-Anzahl. Bei Pflaumenarten wird h\u00e4ufig eine Mehrpunktheizung verwendet (siehe Bild a). Der Durchmesser jedes Punktes d sollte beim Erhitzen der dicken Platte entsprechend gr\u00f6\u00dfer sein, und die d\u00fcnne Platte sollte kleiner sein, der im Allgemeinen nicht weniger als 15 mm betragen sollte.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/2-1-1024x418.jpg\" alt=\"Heizmethode\" class=\"wd-lazy-fade wp-image-2048\" width=\"512\" height=\"209\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/2-1-1024x418.jpg 1024w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/2-1-150x61.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/2-1-300x122.jpg 300w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/2-1-768x313.jpg 768w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/2-1-600x245.jpg 600w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/2-1.jpg 1101w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><figcaption>Heizmethode<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Je gr\u00f6\u00dfer die Deformation, desto kleiner der Abstand zwischen den Punkten a, im Allgemeinen 50-100mm Heizflamme bewegt sich in gerader Richtung oder gleichzeitig in Breitenrichtung eines bestimmten Querhubs, genannt lineare Erw\u00e4rmung (siehe Bild b). Es hat direkte Heizung, Kettenheizung und Bandheizung 3 Arten. Die Querschrumpfung des Hei\u00dfdrahtes ist im Allgemeinen gr\u00f6\u00dfer als die L\u00e4ngsschrumpfung, und der Schrumpfbetrag nimmt mit zunehmender Breite des Hei\u00dfdrahts zu. Die Breite des Hei\u00dfdrahtes betr\u00e4gt im Allgemeinen das 0,5- bis 2-fache der Dicke des Stahls. Lineare Erw\u00e4rmung wird im Allgemeinen f\u00fcr Strukturen mit gro\u00dfer Verformung verwendet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei dreieckiger Heizfl\u00e4che spricht man von Dreiecksheizung (siehe Bild c). Da die Heizfl\u00e4che gro\u00df ist, ist die Schrumpfung gro\u00df, und da die Heizbreite entlang der H\u00f6he der Dreiecksrichtung nicht gleich ist, ist die Schrumpfung nicht gleich, also ist die Biegeverformung auch gro\u00df, oft verwendet bei der Biegeverformungskorrektur von St\u00e4ben mit gr\u00f6\u00dferer Steifigkeit und gr\u00f6\u00dferer Verformung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die folgende Tabelle zeigt g\u00e4ngige Methoden zur Acetylen-Flammenkorrektur f\u00fcr Stahl.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Leer<\/td><td class=\"has-text-align-center\" data-align=\"center\">Urspr\u00fcngliche Verformung<\/td><td class=\"has-text-align-center\" data-align=\"center\">Heizmethode<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bild<\/td><td class=\"has-text-align-center\" data-align=\"center\">Beschreibung<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><br><br>D\u00fcnne Stahlplatte (Dicke nicht gr\u00f6\u00dfer als 8 mm)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><br><br><br>Mittlere Ausbuchtung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><br><br><br>Punktheizung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><br><br><img decoding=\"async\" width=\"377\" height=\"255\" class=\"wd-lazy-fade wp-image-2049\" style=\"width: 150px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/3-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/3-1.jpg 377w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/3-1-150x101.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/3-1-300x203.jpg 300w\" sizes=\"(max-width: 377px) 100vw, 377px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Verwenden Sie Kama-N\u00e4gel mit dem konvexen Teil nach oben. Der Heizpunktabstand betr\u00e4gt 50-100 mm und der Verformungsbetrag ist ein kleiner Wert. Der Durchmesser des Heizflecks betr\u00e4gt 15 mm und die Plattendicke ist der gr\u00f6\u00dfere Wert. Punkte: Je gr\u00f6\u00dfer der Verformungsbereich ist, desto gr\u00f6\u00dfer ist der Punkt. Der Heizablauf ist in der Abbildung dargestellt, erg\u00e4nzt durch H\u00e4mmern<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><br><br>D\u00fcnne Stahlplatte (Dicke nicht gr\u00f6\u00dfer als 8 mm)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><br><br><br>Mittlere Ausbuchtung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><br><br><br>Lineare Erw\u00e4rmung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><br><br><br><img decoding=\"async\" width=\"371\" height=\"243\" class=\"wd-lazy-fade wp-image-2050\" style=\"width: 150px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/4-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/4-1.jpg 371w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/4-1-150x98.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/4-1-300x196.jpg 300w\" sizes=\"(max-width: 371px) 100vw, 371px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Der konvexe Teil zeigt nach oben und wird auf die Plattform geklebt. Es gibt drei Arten von Heizlinienspuren: gerade Linie, Wellenlinie und Spirallinie. Die Breite der beiden letztgenannten betr\u00e4gt (0,5-2)t. Der L\u00e4ngsschrumpf entlang der Heizstrecke ist kleiner als der Querschrumpf. Wenn die Verformung gro\u00df ist, kann die Linienbreite erh\u00f6ht und der Linienabstand verringert werden<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">D\u00fcnne Stahlplatte (Dicke nicht gr\u00f6\u00dfer als 8 mm)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br>Auf einer Seite wellig<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br>Lineare Erw\u00e4rmung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><img decoding=\"async\" width=\"385\" height=\"189\" class=\"wd-lazy-fade wp-image-2051\" style=\"width: 150px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/5-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/5-1.jpg 385w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/5-1-150x74.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/5-1-300x147.jpg 300w\" sizes=\"(max-width: 385px) 100vw, 385px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Klemmen Sie mit dem konvexen Teil nach oben die drei unverformten Seiten fest, erhitzen Sie zuerst beide Seiten des konvexen Teils und umgeben Sie dann den konvexen Teil, um das Erhitzen zu wiederholen<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><br><br>Dicke Stahlplatte<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><br>Bogenbiegung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br>Lineare Erw\u00e4rmung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><img decoding=\"async\" width=\"364\" height=\"134\" class=\"wd-lazy-fade wp-image-2052\" style=\"width: 500px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/6-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/6-1.jpg 364w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/6-1-150x55.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/6-1-300x110.jpg 300w\" sizes=\"(max-width: 364px) 100vw, 364px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Legen Sie es auf die Plattform und erhitzen Sie es vom h\u00f6chsten Punkt auf 600-800\u2103, die Heiztiefe \u00fcberschreitet nicht 1\/3 der Dicke der Platte und kann wiederholt erhitzt werden<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><br><br>Stahlrohr<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br>Biege<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br>Punktheizung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><br><br><img decoding=\"async\" width=\"364\" height=\"123\" class=\"wd-lazy-fade wp-image-2054\" style=\"width: 300px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/7-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/7-1.jpg 364w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/7-1-150x51.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/7-1-300x101.jpg 300w\" sizes=\"(max-width: 364px) 100vw, 364px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Erhitzen der konvexen Oberfl\u00e4che (eine Punktreihe oder mehrere Punktreihen), die Geschwindigkeit von Punkt zu Punkt sollte schnell sein, Erhitzen Reihe f\u00fcr Reihe<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T-f\u00f6rmiger Stahl<\/td><td class=\"has-text-align-center\" data-align=\"center\">Seitliche Biegung<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dreieckheizung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"329\" height=\"130\" class=\"wd-lazy-fade wp-image-2055\" style=\"width: 1000px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/8-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/8-1.jpg 329w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/8-1-150x59.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/8-1-300x119.jpg 300w\" sizes=\"(max-width: 329px) 100vw, 329px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Erhitzen Sie den gew\u00f6lbten Teil der horizontalen Platte<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T-f\u00f6rmiger Stahl<\/td><td class=\"has-text-align-center\" data-align=\"center\">Seitliche Biegung<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dreieckheizung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"363\" height=\"168\" class=\"wd-lazy-fade wp-image-2056\" style=\"width: 150px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/9-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/9-1.jpg 363w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/9-1-150x69.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/9-1-300x139.jpg 300w\" sizes=\"(max-width: 363px) 100vw, 363px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Erhitzen des gew\u00f6lbten Teils der vertikalen Platte<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Winkelstahl<\/td><td class=\"has-text-align-center\" data-align=\"center\">Au\u00dfenbogen<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dreieckheizung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"299\" height=\"134\" class=\"wd-lazy-fade wp-image-2057\" style=\"width: 1500px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/10-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/10-1.jpg 299w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/10-1-150x67.jpg 150w\" sizes=\"(max-width: 299px) 100vw, 299px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Beheizen des erh\u00f6hten Bereichs<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Ich gl\u00e4nze<\/td><td class=\"has-text-align-center\" data-align=\"center\">Seitliche Biegung<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dreieckheizung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"348\" height=\"139\" class=\"wd-lazy-fade wp-image-2058\" style=\"width: 1500px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/11-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/11-1.jpg 348w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/11-1-150x60.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/11-1-300x120.jpg 300w\" sizes=\"(max-width: 348px) 100vw, 348px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Beheizen des erh\u00f6hten Bereichs<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Kanal Stahl<\/td><td class=\"has-text-align-center\" data-align=\"center\">Teilweise Seitenbiegung<\/td><td class=\"has-text-align-center\" data-align=\"center\">Lineare Erw\u00e4rmung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"348\" height=\"150\" class=\"wd-lazy-fade wp-image-2059\" style=\"width: 1500px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/12-2.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/12-2.jpg 348w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/12-2-150x65.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/12-2-300x129.jpg 300w\" sizes=\"(max-width: 348px) 100vw, 348px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\">Zwei Schwei\u00dfbrenner werden gleichzeitig wellenf\u00f6rmig erhitzt<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Stahlzylinder<\/td><td class=\"has-text-align-center\" data-align=\"center\">Lokale Kr\u00fcmmung ist zu gro\u00df<\/td><td class=\"has-text-align-center\" data-align=\"center\">Lineare Erw\u00e4rmung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"339\" height=\"106\" class=\"wd-lazy-fade wp-image-2060\" style=\"width: 1500px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/13-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/13-1.jpg 339w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/13-1-150x47.jpg 150w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/13-1-300x94.jpg 300w\" sizes=\"(max-width: 339px) 100vw, 339px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><br>Heizung entlang der Sammelschiene<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Stahlzylinder<\/td><td class=\"has-text-align-center\" data-align=\"center\">Lokale Kr\u00fcmmung ist zu klein<\/td><td class=\"has-text-align-center\" data-align=\"center\">Lineare Erw\u00e4rmung<\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"301\" height=\"90\" class=\"wd-lazy-fade wp-image-2061\" style=\"width: 2000px\" src=\"https:\/\/hecter.cn\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/14-1.jpg\" alt=\"\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/14-1.jpg 301w, https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/14-1-150x45.jpg 150w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><br>Heizung entlang der Sammelschiene<\/td><\/tr><\/tbody><\/table><figcaption>G\u00e4ngige Acetylen-Flammenkorrekturmethode f\u00fcr Stahl<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-precautions-for-flame-correction-operation\"><strong>Vorsichtsma\u00dfnahmen f\u00fcr den Flammenkorrekturbetrieb<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Die Heizgeschwindigkeit sollte schnell sein, die Hitze sollte konzentriert werden und der Heizbereich au\u00dferhalb des Heizbereichs sollte so gut wie m\u00f6glich eingeengt werden. Die T-Probe kann den Korrektureffekt verbessern und eine gr\u00f6\u00dfere lokale Kontraktion erzielen. Beim Korrigieren des gro\u00dfen Verformungsbereichs, egal ob Mehrpunkt- oder Mehrlinienheizung, darf sich der Erw\u00e4rmungsbereich nicht \u00fcberlappen, da sonst das Werkst\u00fcckmaterial besch\u00e4digt wird. Vor der Korrektur sollten Punkte, Linien und Laufrichtungen der Chargenheizung entsprechend der Gr\u00f6\u00dfe der Verformungsfl\u00e4che und dem Verformungsgrad abgegrenzt werden. Alle Punkte und Linien des gleichen Loses m\u00fcssen mit Abst\u00e4nden, symmetrisch und springend \u00fcber die gesamte Fl\u00e4che verteilt werden. Der gesamte Erw\u00e4rmungsprozess sollte in Chargen durchgef\u00fchrt werden. Wenn eine Charge die Korrekturanforderungen erf\u00fcllt, ist es nicht erforderlich, die n\u00e4chste Erw\u00e4rmungscharge durchzuf\u00fchren. Korrekturverfahren ohne allgemeine Vereinbarung sind untersagt. Dies kann nicht nur den Korrektureffekt sicherstellen, sondern auch das Ph\u00e4nomen der \u00dcberlappung des Heizbereichs vermeiden. Die Abfolge der Hot Spots und Linienpositionen jeder Sandcharge muss am Rand des verformten Bereichs beginnen. Eine zu starke Zentralheizung in der Mitte des verformten Bereichs ist verboten. Andernfalls kommt es zu einer \u00fcberm\u00e4\u00dfigen Verformung im deformierten Gebiet und eine nachtr\u00e4gliche Korrektur wird aufgrund der d\u00f6rflichen Qualit\u00e4t des Gebiets schwierig.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Bei der eigentlichen Korrekturarbeit, oft nach dem Erhitzen von Wasser, um den Heizbereich abzuschrecken, um die Metallkontraktion zu beschleunigen, verbessern Sie die Korrektureffizienz. Im Vergleich zur einfachen Flammenkorrektur l\u00e4sst sich der Effekt um ein Vielfaches steigern, die Methode wird auch als Wasser- und Feuerkorrekturmethode bezeichnet. Die Wasser- und Feuerkorrekturmethode hat bestimmte Einschr\u00e4nkungen. Wenn die richtige Dicke der kohlenstoffarmen Stahlplatte 2 mm betr\u00e4gt, betr\u00e4gt die Heiztemperatur im Allgemeinen nicht mehr als 600 \u00b0 C. Zu diesem Zeitpunkt sollte der Abstand zwischen Wasser und Feuer geringer sein. Wenn die richtige Dicke 4 bis 6 mm Stahlblech betr\u00e4gt, sollte die Heiztemperatur 600-800 \u00b0 C betragen, der Abstand zwischen Wasser und Feuer betr\u00e4gt 25-30 mm. Bei Korrekturen von Stahlblechen mit Dicken \u00fcber 8 mm wird eine Wasserk\u00fchlung im Allgemeinen nicht in Betracht gezogen, da eine Wasserk\u00fchlung gr\u00f6\u00dfere Belastungen verursacht. Beim Korrigieren von Stahlblechen, die zum H\u00e4rten neigen (wie gew\u00f6hnliche niedriglegierte Stahlbleche), sollte der Abstand zwischen Wasser und Feuer gr\u00f6\u00dfer sein. F\u00fcr Materialien mit starker H\u00e4rtungsneigung (wie Stahl mit mittlerem und hohem Kohlenstoffgehalt oder legierter Stahl) k\u00f6nnen keine Wasser- und Feuerkorrekturmethoden angewendet werden, und es kann nur ein gewisser Grad an Luftk\u00fchlung durchgef\u00fchrt werden, um den Verformungsgrad zu verst\u00e4rken. Beim Korrigieren der Biegung der Stahlplatte sollte die Heiztiefe in 1\/4~1\/3 der Dicke der Platte kontrolliert werden. Es sollte nicht zu tief sein, da es sonst die Wirkung der Flammenkorrektur stark beeinflusst.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Obwohl die Flammenkorrektur ein bedeutenderes Korrekturverfahren ist, ist es immer noch schlecht in der Kontrollf\u00e4higkeit des Ausma\u00dfes der Korrekturverformung, insbesondere f\u00fcr das Werkst\u00fcck, das besonders empfindlich auf den Effekt der Flammenkorrektur reagiert, wie z. B. das Richten schlanker Teile und das Richten von d\u00fcnnen Plattenteilen. Daher kann zur Korrektur gro\u00dfer Verformungen dieser Art von Werkst\u00fcck die Flammenkorrektur nur als grobes Korrekturverfahren verwendet werden und sollte mit der nachfolgenden mechanischen Korrektur abgestimmt werden; Die Flammkorrektur sollte nicht zur Korrektur solcher Werkst\u00fccke mit geringer Verformung und h\u00f6heren Anforderungen verwendet werden, da es sonst zu neuen oder noch gr\u00f6\u00dferen Verformungen kommt.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Um das Zusammenziehen der Heizzone zu beschleunigen, gibt es oft einen Hammer, erg\u00e4nzt aber um einen Holzhammer oder einen Kupferhammer, nicht den Hammer.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>In the thermal correction of sheet metal, the most widely used is the oxyacetylene flame correction. Flame correction is not<\/p>","protected":false},"author":3,"featured_media":2063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[856,822,824],"class_list":["post-2045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shearing-machine","tag-metalworking","tag-sheet-metal","tag-sheet-metal-processing"],"jetpack_featured_media_url":"https:\/\/hecter.cn\/wp-content\/uploads\/2021\/05\/Heating-part.jpg","_links":{"self":[{"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/posts\/2045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/comments?post=2045"}],"version-history":[{"count":0,"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/posts\/2045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/media\/2063"}],"wp:attachment":[{"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/media?parent=2045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/categories?post=2045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hecter.cn\/de\/wp-json\/wp\/v2\/tags?post=2045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}